{"id":90,"count":1,"description":"","link":"http:\/\/playfighting.ca\/combat\/tag\/film-riot\/","name":"Film Riot","slug":"film-riot","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"noindex, max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"http:\/\/playfighting.ca\/combat\/tag\/film-riot\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/playfighting.ca\\\/combat\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/90\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/playfighting.ca\\\/combat#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/playfighting.ca\\\/combat\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/playfighting.ca\\\/combat\\\/tag\\\/film-riot\\\/#listItem\",\"name\":\"Film Riot\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/playfighting.ca\\\/combat\\\/tag\\\/film-riot\\\/#listItem\",\"position\":2,\"name\":\"Film Riot\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/playfighting.ca\\\/combat#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"http:\\\/\\\/playfighting.ca\\\/combat\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/90\\\/#collectionpage\",\"url\":\"http:\\\/\\\/playfighting.ca\\\/combat\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/90\\\/\",\"name\":\"Film Riot | PlayFighting\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/playfighting.ca\\\/combat\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/playfighting.ca\\\/combat\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/90\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/playfighting.ca\\\/combat\\\/#organization\",\"name\":\"PlayFighting\",\"description\":\"Vancouver Combat Instruction\",\"url\":\"http:\\\/\\\/playfighting.ca\\\/combat\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/playfighting.ca\\\/combat\\\/#website\",\"url\":\"http:\\\/\\\/playfighting.ca\\\/combat\\\/\",\"name\":\"PlayFighting\",\"description\":\"Vancouver Combat Instruction\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"http:\\\/\\\/playfighting.ca\\\/combat\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Film Riot | PlayFighting","description":"","canonical_url":"http:\/\/playfighting.ca\/combat\/tag\/film-riot\/","robots":"noindex, max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"http:\/\/playfighting.ca\/combat\/wp-json\/wp\/v2\/tags\/90\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"http:\/\/playfighting.ca\/combat#listItem","position":1,"name":"Home","item":"http:\/\/playfighting.ca\/combat","nextItem":{"@type":"ListItem","@id":"http:\/\/playfighting.ca\/combat\/tag\/film-riot\/#listItem","name":"Film Riot"}},{"@type":"ListItem","@id":"http:\/\/playfighting.ca\/combat\/tag\/film-riot\/#listItem","position":2,"name":"Film Riot","previousItem":{"@type":"ListItem","@id":"http:\/\/playfighting.ca\/combat#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"http:\/\/playfighting.ca\/combat\/wp-json\/wp\/v2\/tags\/90\/#collectionpage","url":"http:\/\/playfighting.ca\/combat\/wp-json\/wp\/v2\/tags\/90\/","name":"Film Riot | PlayFighting","inLanguage":"en-US","isPartOf":{"@id":"http:\/\/playfighting.ca\/combat\/#website"},"breadcrumb":{"@id":"http:\/\/playfighting.ca\/combat\/wp-json\/wp\/v2\/tags\/90\/#breadcrumblist"}},{"@type":"Organization","@id":"http:\/\/playfighting.ca\/combat\/#organization","name":"PlayFighting","description":"Vancouver Combat Instruction","url":"http:\/\/playfighting.ca\/combat\/"},{"@type":"WebSite","@id":"http:\/\/playfighting.ca\/combat\/#website","url":"http:\/\/playfighting.ca\/combat\/","name":"PlayFighting","description":"Vancouver Combat Instruction","inLanguage":"en-US","publisher":{"@id":"http:\/\/playfighting.ca\/combat\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/playfighting.ca\/combat\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tFilm Riot\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"http:\/\/playfighting.ca\/combat"},{"label":"Film Riot","link":"http:\/\/playfighting.ca\/combat\/tag\/film-riot\/"}],"_links":{"self":[{"href":"http:\/\/playfighting.ca\/combat\/wp-json\/wp\/v2\/tags\/90"}],"collection":[{"href":"http:\/\/playfighting.ca\/combat\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/playfighting.ca\/combat\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/playfighting.ca\/combat\/wp-json\/wp\/v2\/posts?tags=90"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}